{"id":6820,"date":"2023-10-19T08:46:48","date_gmt":"2023-10-19T06:46:48","guid":{"rendered":"https:\/\/transientimpuls.com\/?post_type=bibliothek&#038;p=6820"},"modified":"2023-12-23T18:28:11","modified_gmt":"2023-12-23T17:28:11","slug":"zwiegespraeche-4-transient-ist-so-viel-mehr-als-nur-drinnen-und-draussen","status":"publish","type":"bibliothek","link":"https:\/\/transientimpuls.com\/en\/bibliothek\/zwiegespraeche-4-transient-ist-so-viel-mehr-als-nur-drinnen-und-draussen\/","title":{"rendered":"Zwiegespr\u00e4che 4: Transient ist so viel mehr als nur drinnen und drau\u00dfen\u2026"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Ein Herzst\u00fcck des Festivals ist die N\u00e4he zu den lokalen Ortschaften und die direkte Zusammenarbeit mit Menschen vor Ort. Ich sage explizit nicht \u201ePublikum\u201c, da es nicht in erster Linie darum geht &#8211; zumindest so meine Wahrnehmung &#8211; die Menschen von der Gro\u00dfartigkeit unseres Projekt zu \u00fcberzeugen und zu Hauf zu den Konzerten zu bewegen, sondern es findet ein <em>Miteinander<\/em> statt und man w\u00fcrdigt das, was vor Ort schon seit langem stattfindet &#8211; ganz ohne, dass man als Berliner K\u00fcnstlernase (in diesem Moment fasse ich mir selbstverst\u00e4ndlich an die eigene Nase) extra dorthin f\u00e4hrt.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">F\u00fcr mich bedeutete dies zum Beispiel ein Workshop mit Jugendlichen des St. Michael Gymnasiums in Blankenheim und eine Urauff\u00fchrung mit dem lokalen Bl\u00e4serverein, komponiert und geleitet von Frank Reinshagen.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Beide Aufgaben waren durchaus eine Herausforderung, zumindest gedanklich im Vorhinein, da meine Hauptt\u00e4tigkeit sich bisher meistens auf Konzerte spielen beschr\u00e4nkt hat.&nbsp;<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/transientimpuls.com\/wp-content\/uploads\/2023\/10\/Maxine-Gymnasium-Innenhof-768x1024.jpg\" alt=\"\" class=\"wp-image-6821\" style=\"width:500px\" srcset=\"https:\/\/transientimpuls.com\/wp-content\/uploads\/2023\/10\/Maxine-Gymnasium-Innenhof-768x1024.jpg 768w, https:\/\/transientimpuls.com\/wp-content\/uploads\/2023\/10\/Maxine-Gymnasium-Innenhof-225x300.jpg 225w, https:\/\/transientimpuls.com\/wp-content\/uploads\/2023\/10\/Maxine-Gymnasium-Innenhof-1152x1536.jpg 1152w, https:\/\/transientimpuls.com\/wp-content\/uploads\/2023\/10\/Maxine-Gymnasium-Innenhof.jpg 1200w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">F\u00fcr den Workshop habe ich die Grundidee des \u201eSoundpainting\u201c Konzepts gew\u00e4hlt &#8211; eine durch Handzeichen angeleitete Gruppen-Improvisation, die keine Vorkenntnisse oder besonderen F\u00e4higkeiten erfordert und bereits in den 1970er Jahren von Walter Thompson entwickelt wurde.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Heutzutage gibt es spezielle Ensembles und Leiter:innen, die sich auf diese Technik spezialisieren und sie mit \u00fcber 500 Handzeichen zu einem ausgekl\u00fcgelten musikalischen System gemacht haben.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diesen Anspruch hatte ich selbstverst\u00e4ndlich nicht &#8211; mein selbsternanntes Ziel war es viel eher, ein Vertrauen zu und unter den Jugendlichen zu entwickeln, das sie dazu bef\u00e4higt, selbstst\u00e4ndige, mutige musikalische Entscheidungen zu treffen, und in der Gruppe zu erleben, wie man <em>gemeinsam<\/em> ohne gro\u00dfe H\u00fcrden etwas Neues, ganz pers\u00f6nliches kreieren kann.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vielleicht lockte mich selbst diese Idee so sehr, da ich erst sp\u00e4t, bereits im Studium, mich mit dem Thema Improvisation besch\u00e4ftigt habe und im Alleingang die Kraft und M\u00f6glichkeiten dieser musikalischen Ausdrucksweise versucht habe, mir zu erschlie\u00dfen.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der Prozess und das Resultat jedenfalls hat mir unglaubliche Freude bereitet &#8211; als Gruppe vor 150-200 Mitsch\u00fcler:innen und anderem Publikum im Freien eine 7-min\u00fctige freie Improvisation vorzuf\u00fchren, die alles andere als sch\u00fcchtern und zur\u00fcckhaltend war, erfordert gro\u00dfen Mut!\u00a0<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/transientimpuls.com\/wp-content\/uploads\/2023\/10\/Maxine-Soundpainting-Performance-768x1024.jpg\" alt=\"\" class=\"wp-image-6822\" style=\"width:500px\" srcset=\"https:\/\/transientimpuls.com\/wp-content\/uploads\/2023\/10\/Maxine-Soundpainting-Performance-768x1024.jpg 768w, https:\/\/transientimpuls.com\/wp-content\/uploads\/2023\/10\/Maxine-Soundpainting-Performance-225x300.jpg 225w, https:\/\/transientimpuls.com\/wp-content\/uploads\/2023\/10\/Maxine-Soundpainting-Performance-1152x1536.jpg 1152w, https:\/\/transientimpuls.com\/wp-content\/uploads\/2023\/10\/Maxine-Soundpainting-Performance.jpg 1200w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Die Zusammenarbeit mit dem Blasverein von Frank Reinshagen war ebenfalls etwas total bereicherndes &#8211; und auch hier stand die Improvisation im Mittelpunkt. Eine Komposition, die ganz wie die Eifel an sich, Platz, Zeit und Raum schafft f\u00fcr feine Konsonanzen und Dissonanzen und mir als Solistin die M\u00f6glichkeit gab, mit dem gegebenen Material wirklich zu <em>spielen <\/em>klangliche Nuancen herauszuarbeiten. Diese Art von Vertrauen, die Frank mir in diesem Rahmen schenkte war und ist keine Selbstverst\u00e4ndlichkeit und ich freue mich bereits \u00fcber die n\u00e4chste M\u00f6glichkeit, mit ihm zusammen arbeiten zu d\u00fcrfen!&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ein Herzst\u00fcck des Festivals ist die N\u00e4he zu den lokalen Ortschaften und die direkte Zusammenarbeit mit Menschen vor Ort. Ich sage explizit nicht \u201ePublikum\u201c, da es nicht in erster Linie darum geht &#8211; zumindest so meine Wahrnehmung &#8211; die Menschen von der Gro\u00dfartigkeit unseres Projekt zu \u00fcberzeugen und zu Hauf zu den Konzerten zu bewegen, [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":6823,"parent":0,"template":"","format":"standard","categories":[],"tags":[],"festivaljahr":[109],"class_list":["post-6820","bibliothek","type-bibliothek","status-publish","format-standard","has-post-thumbnail","hentry","festivaljahr-109"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Zwiegespr\u00e4che 4: Transient ist so viel mehr als nur drinnen und drau\u00dfen\u2026 &#8226; TRANSIENT Labor und Academy 2022<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/transientimpuls.com\/bibliothek\/zwiegespraeche-4-transient-ist-so-viel-mehr-als-nur-drinnen-und-draussen\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zwiegespr\u00e4che 4: Transient ist so viel mehr als nur drinnen und drau\u00dfen\u2026 &#8226; TRANSIENT Labor und Academy 2022\" \/>\n<meta property=\"og:description\" content=\"Ein Herzst\u00fcck des Festivals ist die N\u00e4he zu den lokalen Ortschaften und die direkte Zusammenarbeit mit Menschen vor Ort. Ich sage explizit nicht \u201ePublikum\u201c, da es nicht in erster Linie darum geht &#8211; zumindest so meine Wahrnehmung &#8211; die Menschen von der Gro\u00dfartigkeit unseres Projekt zu \u00fcberzeugen und zu Hauf zu den Konzerten zu bewegen, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/transientimpuls.com\/bibliothek\/zwiegespraeche-4-transient-ist-so-viel-mehr-als-nur-drinnen-und-draussen\/\" \/>\n<meta property=\"og:site_name\" content=\"TRANSIENT Labor und Academy 2022\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TransientImpuls\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-23T17:28:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/transientimpuls.com\/wp-content\/uploads\/2023\/10\/Maxine-Soundpainting-Performance-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/transientimpuls.com\/bibliothek\/zwiegespraeche-4-transient-ist-so-viel-mehr-als-nur-drinnen-und-draussen\/\",\"url\":\"https:\/\/transientimpuls.com\/bibliothek\/zwiegespraeche-4-transient-ist-so-viel-mehr-als-nur-drinnen-und-draussen\/\",\"name\":\"Zwiegespr\u00e4che 4: Transient ist so viel mehr als nur drinnen und drau\u00dfen\u2026 &#8226; TRANSIENT Labor und Academy 2022\",\"isPartOf\":{\"@id\":\"https:\/\/transientimpuls.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/transientimpuls.com\/bibliothek\/zwiegespraeche-4-transient-ist-so-viel-mehr-als-nur-drinnen-und-draussen\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/transientimpuls.com\/bibliothek\/zwiegespraeche-4-transient-ist-so-viel-mehr-als-nur-drinnen-und-draussen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/transientimpuls.com\/wp-content\/uploads\/2023\/10\/Maxine-Soundpainting-Performance-1.jpg\",\"datePublished\":\"2023-10-19T06:46:48+00:00\",\"dateModified\":\"2023-12-23T17:28:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/transientimpuls.com\/bibliothek\/zwiegespraeche-4-transient-ist-so-viel-mehr-als-nur-drinnen-und-draussen\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/transientimpuls.com\/bibliothek\/zwiegespraeche-4-transient-ist-so-viel-mehr-als-nur-drinnen-und-draussen\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/transientimpuls.com\/bibliothek\/zwiegespraeche-4-transient-ist-so-viel-mehr-als-nur-drinnen-und-draussen\/#primaryimage\",\"url\":\"https:\/\/transientimpuls.com\/wp-content\/uploads\/2023\/10\/Maxine-Soundpainting-Performance-1.jpg\",\"contentUrl\":\"https:\/\/transientimpuls.com\/wp-content\/uploads\/2023\/10\/Maxine-Soundpainting-Performance-1.jpg\",\"width\":1200,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/transientimpuls.com\/bibliothek\/zwiegespraeche-4-transient-ist-so-viel-mehr-als-nur-drinnen-und-draussen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/transientimpuls.com\/en\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bibliothek\",\"item\":\"https:\/\/transientimpuls.com\/bibliothek\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Zwiegespr\u00e4che 4: Transient ist so viel mehr als nur drinnen und drau\u00dfen\u2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/transientimpuls.com\/#website\",\"url\":\"https:\/\/transientimpuls.com\/\",\"name\":\"TRANSIENT Kulturprojekte\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/transientimpuls.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/transientimpuls.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/transientimpuls.com\/#organization\",\"name\":\"TRANSIENT Labor und Academy 2022\",\"url\":\"https:\/\/transientimpuls.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/transientimpuls.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/transientimpuls.com\/wp-content\/uploads\/2022\/07\/transient_labor-academy-2022.svg\",\"contentUrl\":\"https:\/\/transientimpuls.com\/wp-content\/uploads\/2022\/07\/transient_labor-academy-2022.svg\",\"width\":1428,\"height\":388,\"caption\":\"TRANSIENT Labor und Academy 2022\"},\"image\":{\"@id\":\"https:\/\/transientimpuls.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/TransientImpuls\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zwiegespr\u00e4che 4: Transient ist so viel mehr als nur drinnen und drau\u00dfen\u2026 &#8226; TRANSIENT Labor und Academy 2022","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/transientimpuls.com\/bibliothek\/zwiegespraeche-4-transient-ist-so-viel-mehr-als-nur-drinnen-und-draussen\/","og_locale":"en_US","og_type":"article","og_title":"Zwiegespr\u00e4che 4: Transient ist so viel mehr als nur drinnen und drau\u00dfen\u2026 &#8226; TRANSIENT Labor und Academy 2022","og_description":"Ein Herzst\u00fcck des Festivals ist die N\u00e4he zu den lokalen Ortschaften und die direkte Zusammenarbeit mit Menschen vor Ort. Ich sage explizit nicht \u201ePublikum\u201c, da es nicht in erster Linie darum geht &#8211; zumindest so meine Wahrnehmung &#8211; die Menschen von der Gro\u00dfartigkeit unseres Projekt zu \u00fcberzeugen und zu Hauf zu den Konzerten zu bewegen, [&hellip;]","og_url":"https:\/\/transientimpuls.com\/bibliothek\/zwiegespraeche-4-transient-ist-so-viel-mehr-als-nur-drinnen-und-draussen\/","og_site_name":"TRANSIENT Labor und Academy 2022","article_publisher":"https:\/\/www.facebook.com\/TransientImpuls","article_modified_time":"2023-12-23T17:28:11+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/transientimpuls.com\/wp-content\/uploads\/2023\/10\/Maxine-Soundpainting-Performance-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/transientimpuls.com\/bibliothek\/zwiegespraeche-4-transient-ist-so-viel-mehr-als-nur-drinnen-und-draussen\/","url":"https:\/\/transientimpuls.com\/bibliothek\/zwiegespraeche-4-transient-ist-so-viel-mehr-als-nur-drinnen-und-draussen\/","name":"Zwiegespr\u00e4che 4: Transient ist so viel mehr als nur drinnen und drau\u00dfen\u2026 &#8226; TRANSIENT Labor und Academy 2022","isPartOf":{"@id":"https:\/\/transientimpuls.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/transientimpuls.com\/bibliothek\/zwiegespraeche-4-transient-ist-so-viel-mehr-als-nur-drinnen-und-draussen\/#primaryimage"},"image":{"@id":"https:\/\/transientimpuls.com\/bibliothek\/zwiegespraeche-4-transient-ist-so-viel-mehr-als-nur-drinnen-und-draussen\/#primaryimage"},"thumbnailUrl":"https:\/\/transientimpuls.com\/wp-content\/uploads\/2023\/10\/Maxine-Soundpainting-Performance-1.jpg","datePublished":"2023-10-19T06:46:48+00:00","dateModified":"2023-12-23T17:28:11+00:00","breadcrumb":{"@id":"https:\/\/transientimpuls.com\/bibliothek\/zwiegespraeche-4-transient-ist-so-viel-mehr-als-nur-drinnen-und-draussen\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/transientimpuls.com\/bibliothek\/zwiegespraeche-4-transient-ist-so-viel-mehr-als-nur-drinnen-und-draussen\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/transientimpuls.com\/bibliothek\/zwiegespraeche-4-transient-ist-so-viel-mehr-als-nur-drinnen-und-draussen\/#primaryimage","url":"https:\/\/transientimpuls.com\/wp-content\/uploads\/2023\/10\/Maxine-Soundpainting-Performance-1.jpg","contentUrl":"https:\/\/transientimpuls.com\/wp-content\/uploads\/2023\/10\/Maxine-Soundpainting-Performance-1.jpg","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/transientimpuls.com\/bibliothek\/zwiegespraeche-4-transient-ist-so-viel-mehr-als-nur-drinnen-und-draussen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/transientimpuls.com\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Bibliothek","item":"https:\/\/transientimpuls.com\/bibliothek\/"},{"@type":"ListItem","position":3,"name":"Zwiegespr\u00e4che 4: Transient ist so viel mehr als nur drinnen und drau\u00dfen\u2026"}]},{"@type":"WebSite","@id":"https:\/\/transientimpuls.com\/#website","url":"https:\/\/transientimpuls.com\/","name":"TRANSIENT Kulturprojekte","description":"","publisher":{"@id":"https:\/\/transientimpuls.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/transientimpuls.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/transientimpuls.com\/#organization","name":"TRANSIENT Labor und Academy 2022","url":"https:\/\/transientimpuls.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/transientimpuls.com\/#\/schema\/logo\/image\/","url":"https:\/\/transientimpuls.com\/wp-content\/uploads\/2022\/07\/transient_labor-academy-2022.svg","contentUrl":"https:\/\/transientimpuls.com\/wp-content\/uploads\/2022\/07\/transient_labor-academy-2022.svg","width":1428,"height":388,"caption":"TRANSIENT Labor und Academy 2022"},"image":{"@id":"https:\/\/transientimpuls.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/TransientImpuls"]}]}},"_links":{"self":[{"href":"https:\/\/transientimpuls.com\/en\/wp-json\/wp\/v2\/bibliothek\/6820","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/transientimpuls.com\/en\/wp-json\/wp\/v2\/bibliothek"}],"about":[{"href":"https:\/\/transientimpuls.com\/en\/wp-json\/wp\/v2\/types\/bibliothek"}],"author":[{"embeddable":true,"href":"https:\/\/transientimpuls.com\/en\/wp-json\/wp\/v2\/users\/11"}],"version-history":[{"count":0,"href":"https:\/\/transientimpuls.com\/en\/wp-json\/wp\/v2\/bibliothek\/6820\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/transientimpuls.com\/en\/wp-json\/wp\/v2\/media\/6823"}],"wp:attachment":[{"href":"https:\/\/transientimpuls.com\/en\/wp-json\/wp\/v2\/media?parent=6820"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/transientimpuls.com\/en\/wp-json\/wp\/v2\/categories?post=6820"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/transientimpuls.com\/en\/wp-json\/wp\/v2\/tags?post=6820"},{"taxonomy":"festivaljahr","embeddable":true,"href":"https:\/\/transientimpuls.com\/en\/wp-json\/wp\/v2\/festivaljahr?post=6820"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}